{"id":96452,"date":"2024-11-18T16:28:28","date_gmt":"2024-11-18T15:28:28","guid":{"rendered":"https:\/\/acperugiacalcio.com\/sponsors\/"},"modified":"2025-10-13T11:10:37","modified_gmt":"2025-10-13T09:10:37","slug":"sponsors","status":"publish","type":"page","link":"https:\/\/acperugiacalcio.com\/en\/sponsors\/","title":{"rendered":"Sponsors"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"96452\" class=\"elementor elementor-96452 elementor-33\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e3fc569 e-con-full e-flex e-con e-parent\" data-id=\"e3fc569\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-481d7a1 e-flex e-con-boxed e-con e-child\" data-id=\"481d7a1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1bbf53d elementor-widget elementor-widget-heading\" data-id=\"1bbf53d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SPONSOR<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e0b0df2 e-con-full e-flex e-con e-parent\" data-id=\"e0b0df2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2891d4b e-con-full e-flex e-con e-child\" data-id=\"2891d4b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-99841b6 e-con-full e-flex e-con e-child\" data-id=\"99841b6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-696bf32 elementor-widget elementor-widget-heading\" data-id=\"696bf32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SECOND sponsor<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1e9d62 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e1e9d62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63ed85d elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"63ed85d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.centralenergy.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/centralenergyperugia.png\" class=\"attachment-full size-full wp-image-96542\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/centralenergyperugia.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/centralenergyperugia-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d1b0ad1 e-con-full e-flex e-con e-child\" data-id=\"d1b0ad1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7d34592 elementor-widget elementor-widget-heading\" data-id=\"7d34592\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">BACK SPONSOR<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8f0f48 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e8f0f48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2a60ac elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"f2a60ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ilcapricorno.eu\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/capricornosponsor.png\" class=\"attachment-full size-full wp-image-96544\" alt=\"capricornosponsor\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/capricornosponsor.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/capricornosponsor-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/capricornosponsor-100x100.png 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-215cb12 e-con-full e-flex e-con e-child\" data-id=\"215cb12\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-33a9149 e-con-full e-flex e-con e-child\" data-id=\"33a9149\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-45c9eca elementor-widget elementor-widget-heading\" data-id=\"45c9eca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SECOND BACK SPONSOR<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-011e6ce elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"011e6ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-375b0ae elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"375b0ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.comune.perugia.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/logo-citta-di-perugia-vettoriale-1.png\" class=\"attachment-full size-full wp-image-96546\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/logo-citta-di-perugia-vettoriale-1.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/logo-citta-di-perugia-vettoriale-1-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/logo-citta-di-perugia-vettoriale-1-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/logo-citta-di-perugia-vettoriale-1-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-416912e e-con-full e-flex e-con e-child\" data-id=\"416912e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5bf4865 elementor-widget elementor-widget-heading\" data-id=\"5bf4865\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SLEEVE SPONSOR<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7cf6f8c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7cf6f8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-382bf43 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"382bf43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mcisrl.com\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/logomci.png\" class=\"attachment-full size-full wp-image-96549\" alt=\"logomci\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/logomci.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/logomci-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/logomci-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/logomci-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-32cd733 e-con-full e-flex e-con e-child\" data-id=\"32cd733\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-91fe4b3 elementor-widget elementor-widget-heading\" data-id=\"91fe4b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SHORT SPONSOR<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4a3c26 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e4a3c26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44900f5 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"44900f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.mericat.it\/it\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/mericatperugia.png\" class=\"attachment-full size-full wp-image-96551\" alt=\"mericatperugia\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/mericatperugia.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/mericatperugia-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/mericatperugia-100x100.png 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-458f776 e-con-full e-flex e-con e-parent\" data-id=\"458f776\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-069b612 e-con-full e-flex e-con e-child\" data-id=\"069b612\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-9b8163b e-con-full e-flex e-con e-child\" data-id=\"9b8163b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78e7c7c elementor-widget elementor-widget-heading\" data-id=\"78e7c7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">TOP SPONSORS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45d9874 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"45d9874\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e552b5b e-con-full e-flex e-con e-child\" data-id=\"e552b5b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0208ed4 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"0208ed4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.conad.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/CONAD.png\" class=\"attachment-full size-full wp-image-96554\" alt=\"CONAD\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/CONAD.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/CONAD-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a825449 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"a825449\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.lascuoladuepuntozero.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/lascuola.png\" class=\"attachment-full size-full wp-image-96556\" alt=\"lascuola\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/lascuola.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/lascuola-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7830810 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"7830810\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.mcdonalds.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/mcdonalds.png\" class=\"attachment-full size-full wp-image-96685\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/mcdonalds.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/mcdonalds-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/mcdonalds-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/mcdonalds-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b95f7d4 e-con-full e-flex e-con e-child\" data-id=\"b95f7d4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ef56d11 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"ef56d11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.cogenlab.com\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/congelablogo.png\" class=\"attachment-full size-full wp-image-96689\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/congelablogo.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/congelablogo-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/congelablogo-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/congelablogo-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b41c55c elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"b41c55c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.gruppogrifo.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/Grifo-latte.png\" class=\"attachment-full size-full wp-image-96558\" alt=\"Grifo-milk\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/Grifo-latte.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/Grifo-latte-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/Grifo-latte-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/Grifo-latte-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ca3f0f elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"5ca3f0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.profilumbra.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/profilumbria.png\" class=\"attachment-full size-full wp-image-96561\" alt=\"https:\/\/www.profilumbra.it\/\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/profilumbria.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/profilumbria-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/profilumbria-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/profilumbria-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0f77aa6 e-con-full e-flex e-con e-parent\" data-id=\"0f77aa6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-9b42ac8 e-con-full e-flex e-con e-child\" data-id=\"9b42ac8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b1c6c64 e-con-full e-flex e-con e-child\" data-id=\"b1c6c64\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ed4c60 elementor-widget elementor-widget-heading\" data-id=\"2ed4c60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">OFFICIAL SPONSOR<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b807944 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b807944\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-12b6b55 e-con-full e-flex e-con e-child\" data-id=\"12b6b55\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78db373 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"78db373\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.scaispa.com\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/SCAI_logo-ufficiale.png\" class=\"attachment-full size-full wp-image-96563\" alt=\"SCAI_logo-official\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/SCAI_logo-ufficiale.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/SCAI_logo-ufficiale-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/SCAI_logo-ufficiale-100x100.png 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f50b7ab elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"f50b7ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/sonora__club\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/sonoraclub.png\" class=\"attachment-full size-full wp-image-96565\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/sonoraclub.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/sonoraclub-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/sonoraclub-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/sonoraclub-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9103148 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"9103148\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.ageallianz.it\/amelia4509000\/?fbclid=IwY2xjawMVRHBleHRuA2FlbQIxMABicmlkETFsa1BoMFV3RVNIMmZ6Q1ZxAR7GdJ1_bUI1uAy9F89MS7xasMPsGezra0FAD3x34HF9Mb7fP87DnDWqamcYXg_aem_9UvLoT5txGJ2UOdkF7upCg\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/allianz.png\" class=\"attachment-full size-full wp-image-96567\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/allianz.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/allianz-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/allianz-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/allianz-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d404d57 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"d404d57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.ristorantepizzeriamaghera.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/maghera.png\" class=\"attachment-full size-full wp-image-96572\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/maghera.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/maghera-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/maghera-100x100.png 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5618254 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"5618254\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.mollofratelli.com\/sedi\/centro-noleggio-di-perugia\/?gad_source=1&#038;gad_campaignid=23046419647&#038;gbraid=0AAAAACxzoDjGZQ6d7EQGTR836S16S3KN4&#038;gclid=CjwKCAjw6P3GBhBVEiwAJPjmLjDC7Q3ot1KkB4lT0YUQpdnwalD8iTLbPLubeHQ5bCAuJkxqgdXUKxoCrfEQAvD_BwE\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/10\/mollo2025.png\" class=\"attachment-full size-full wp-image-96570\" alt=\"mollo2025\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/10\/mollo2025.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/10\/mollo2025-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/10\/mollo2025-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/10\/mollo2025-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9cf5d26 e-con-full e-flex e-con e-child\" data-id=\"9cf5d26\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-db55be4 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"db55be4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/people\/Segnaletica-Centro-Italia-Riunita\/61566780668558\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/scir.png\" class=\"attachment-full size-full wp-image-96581\" alt=\"scir\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/scir.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/scir-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2fac7e elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"c2fac7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.gervasiimpianti.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/gervasi-1.png\" class=\"attachment-full size-full wp-image-96574\" alt=\"gervasi\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/gervasi-1.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/gervasi-1-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5bc2da elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"a5bc2da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.globalservicegestioni.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/global.png\" class=\"attachment-full size-full wp-image-96576\" alt=\"global service\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/global.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/global-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b393cc elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"0b393cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.ticketone.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/ticketoneperugia.png\" class=\"attachment-full size-full wp-image-96590\" alt=\"ticketoneperugia\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/ticketoneperugia.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/ticketoneperugia-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/ticketoneperugia-100x100.png 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b78d14d e-con-full e-flex e-con e-child\" data-id=\"b78d14d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5d78cc1 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"5d78cc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/gandolfiimmobilare.png\" class=\"attachment-full size-full wp-image-96657\" alt=\"gandolfiimmobilare\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/gandolfiimmobilare.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/gandolfiimmobilare-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/gandolfiimmobilare-100x100.png 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93eb32f elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"93eb32f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.newconstructioncompany.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/newconstruction.png\" class=\"attachment-full size-full wp-image-96593\" alt=\"newconstruction\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/newconstruction.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/newconstruction-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/newconstruction-100x100.png 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e532a8 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"6e532a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.riccini.info\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/riccini.png\" class=\"attachment-full size-full wp-image-96583\" alt=\"hedgehogs\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/riccini.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/riccini-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21b3dc2 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"21b3dc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/progettofuoco.net\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/progettofuoco.png\" class=\"attachment-full size-full wp-image-96588\" alt=\"projectfire\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/progettofuoco.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/progettofuoco-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-74c7dc8 e-con-full e-flex e-con e-child\" data-id=\"74c7dc8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-600cb69 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"600cb69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/quoredipanna.png\" class=\"attachment-full size-full wp-image-96693\" alt=\"quoredipanna\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/quoredipanna.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/quoredipanna-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/quoredipanna-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/quoredipanna-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-934cff5 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"934cff5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.novaplastpg.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/Novaplast.png\" class=\"attachment-full size-full wp-image-96579\" alt=\"Novaplast\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/Novaplast.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/Novaplast-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8eba75f elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"8eba75f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/tiberinacarnisnc\/?locale=it_IT\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/tiberinacarni.png\" class=\"attachment-full size-full wp-image-96602\" alt=\"tiberinacarni\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/tiberinacarni.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/tiberinacarni-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b81a3fe elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"b81a3fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.riccini.info\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/flliciotti.png\" class=\"attachment-full size-full wp-image-96691\" alt=\"flliciotti\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/flliciotti.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/flliciotti-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/flliciotti-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/flliciotti-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2f390d1 e-con-full e-flex e-con e-child\" data-id=\"2f390d1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b97f465 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"b97f465\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.autoscuolagrifo.net\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/Autoscuola-Grifo-logo.png\" class=\"attachment-full size-full wp-image-96595\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/Autoscuola-Grifo-logo.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/Autoscuola-Grifo-logo-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/Autoscuola-Grifo-logo-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/Autoscuola-Grifo-logo-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-661f09b elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"661f09b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.italysrlcostruzioni.com\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/Logo-Italy-2019-HRlogo.png\" class=\"attachment-full size-full wp-image-96600\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/Logo-Italy-2019-HRlogo.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/Logo-Italy-2019-HRlogo-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/Logo-Italy-2019-HRlogo-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/Logo-Italy-2019-HRlogo-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bdc214c elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"bdc214c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/dolcevitaperugia\/?locale=it_IT\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/dolcevitaperugia.png\" class=\"attachment-full size-full wp-image-96586\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/dolcevitaperugia.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/dolcevitaperugia-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/dolcevitaperugia-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/dolcevitaperugia-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b99346e elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"b99346e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/Logo-Gjuraj-NUOVO-bfc.png\" class=\"attachment-full size-full wp-image-96672\" alt=\"Logo-Gjuraj-NOW-bfc\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/Logo-Gjuraj-NUOVO-bfc.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/Logo-Gjuraj-NUOVO-bfc-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/Logo-Gjuraj-NUOVO-bfc-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/Logo-Gjuraj-NUOVO-bfc-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df1c7ff elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"df1c7ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.tankard.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/tankard.png\" class=\"attachment-full size-full wp-image-96597\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/tankard.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/tankard-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/tankard-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/tankard-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3a2d233 e-con-full e-flex e-con e-parent\" data-id=\"3a2d233\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-be59283 e-con-full e-flex e-con e-child\" data-id=\"be59283\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ed226ed e-con-full e-flex e-con e-child\" data-id=\"ed226ed\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8fa267b elementor-widget elementor-widget-heading\" data-id=\"8fa267b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HOSPITALITY PARTNER<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e07d9d elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8e07d9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6d5fc8d e-con-full e-flex e-con e-child\" data-id=\"6d5fc8d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0a60e3d elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"0a60e3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.menchetti.it\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/menchetti.png\" class=\"attachment-full size-full wp-image-96604\" alt=\"menchetti\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/menchetti.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/menchetti-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-460a24a elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"460a24a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.cantinabaldassarri.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/cantinabaldassari.png\" class=\"attachment-full size-full wp-image-96606\" alt=\"cantinabaldassari\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/cantinabaldassari.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/cantinabaldassari-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa32f35 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"fa32f35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.selfcaffe.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/selfcaffe.png\" class=\"attachment-full size-full wp-image-96608\" alt=\"selfcaffe\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/selfcaffe.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/selfcaffe-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eaa79c3 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"eaa79c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.beamodelagency.com\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/beamodel.png\" class=\"attachment-full size-full wp-image-96611\" alt=\"beamodel\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/beamodel.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/beamodel-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47a1979 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"47a1979\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/aqua-matic.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/aquamatic.png\" class=\"attachment-full size-full wp-image-96613\" alt=\"aquamatic\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/aquamatic.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/aquamatic-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8d63b9f e-con-full e-flex e-con e-parent\" data-id=\"8d63b9f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a7d2907 e-con-full e-flex e-con e-child\" data-id=\"a7d2907\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-26a9eb3 e-con-full e-flex e-con e-child\" data-id=\"26a9eb3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3f6b7c4 elementor-widget elementor-widget-heading\" data-id=\"3f6b7c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CAR PARTNER<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d03dc0 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1d03dc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-62dc897 e-con-full e-flex e-con e-child\" data-id=\"62dc897\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-43d0eb1 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"43d0eb1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.ambrosispa.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/volvo-ambrosi.png\" class=\"attachment-full size-full wp-image-96616\" alt=\"volvo-ambrosi\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/volvo-ambrosi.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/volvo-ambrosi-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7febe37 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"7febe37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.admotor.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/admotor.png\" class=\"attachment-full size-full wp-image-96618\" alt=\"admotor\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/admotor.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/admotor-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae063c2 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"ae063c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tombolinimotor.com\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/tombolini.png\" class=\"attachment-full size-full wp-image-96623\" alt=\"tombolini\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/tombolini.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/tombolini-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b52558f elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"b52558f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.car-one.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"242\" height=\"242\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/carone.png\" class=\"attachment-full size-full wp-image-96620\" alt=\"caron\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/carone.png 242w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/carone-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/carone-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/carone-50x50.png 50w\" sizes=\"(max-width: 242px) 100vw, 242px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b898287 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"b898287\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/fratellipalomba.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/palomba.png\" class=\"attachment-full size-full wp-image-96625\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/palomba.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/palomba-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/palomba-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/palomba-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1c302a7 e-con-full e-flex e-con e-parent\" data-id=\"1c302a7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d5a6e2f e-con-full e-flex e-con e-child\" data-id=\"d5a6e2f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ce0ef3a e-con-full e-flex e-con e-child\" data-id=\"ce0ef3a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78c901c elementor-widget elementor-widget-heading\" data-id=\"78c901c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">MEDICAL PARTNER<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8923536 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8923536\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3d6a88d e-con-full e-flex e-con e-child\" data-id=\"3d6a88d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1893a70 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"1893a70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.sixtusitalia.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/sixtus.png\" class=\"attachment-full size-full wp-image-96627\" alt=\"sixtus\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/sixtus.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/sixtus-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1aaf9f1 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"1aaf9f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.casadicuraliotti.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/casacuraliotti.png\" class=\"attachment-full size-full wp-image-96647\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/casacuraliotti.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/casacuraliotti-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/casacuraliotti-100x100.png 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7cd0262 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"7cd0262\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/quasarmedicalcenter.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/quasarcentralmedical.png\" class=\"attachment-full size-full wp-image-96680\" alt=\"quasarcentralmedical\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/quasarcentralmedical.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/quasarcentralmedical-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/quasarcentralmedical-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/quasarcentralmedical-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7dd8a4b e-con-full e-flex e-con e-child\" data-id=\"7dd8a4b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e175cbd elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"e175cbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fisiosalusperugia.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/fisiosalus.png\" class=\"attachment-full size-full wp-image-96682\" alt=\"physiosalus\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/fisiosalus.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/fisiosalus-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/fisiosalus-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/fisiosalus-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1b936f elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"e1b936f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/labgaleno.com\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/galeno.png\" class=\"attachment-full size-full wp-image-96684\" alt=\"galen\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/galeno.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/galeno-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/galeno-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/galeno-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d03a7d elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"6d03a7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.medisportcenter.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/10\/medisport.png\" class=\"attachment-full size-full wp-image-96671\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/10\/medisport.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/10\/medisport-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/10\/medisport-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/10\/medisport-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b7a7309 e-con-full e-flex e-con e-parent\" data-id=\"b7a7309\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5923970 e-con-full e-flex e-con e-child\" data-id=\"5923970\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f557080 e-con-full e-flex e-con e-child\" data-id=\"f557080\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ba9beb elementor-widget elementor-widget-heading\" data-id=\"7ba9beb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">OFFICIAL SUPPLIER<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a54c3f0 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a54c3f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b38c035 e-con-full e-flex e-con e-child\" data-id=\"b38c035\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dac3eb3 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"dac3eb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.airport.umbria.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/Aeroporto-dellUmbria.png\" class=\"attachment-full size-full wp-image-96630\" alt=\"Airport-of-Umbria\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/Aeroporto-dellUmbria.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/Aeroporto-dellUmbria-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/Aeroporto-dellUmbria-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/Aeroporto-dellUmbria-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2cf422 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"a2cf422\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.riccisrl.net\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/riccigs.png\" class=\"attachment-full size-full wp-image-96635\" alt=\"riccigs\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/riccigs.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/riccigs-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b16357f elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"b16357f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/puliumbriagroupservice.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/puliumbria.png\" class=\"attachment-full size-full wp-image-96637\" alt=\"puliumbria\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/puliumbria.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/puliumbria-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4569543 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"4569543\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.vegatecnoservice.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/vegatecnoservice.png\" class=\"attachment-full size-full wp-image-96709\" alt=\"vegatecnoservice\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/vegatecnoservice.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/vegatecnoservice-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a740a9e elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"a740a9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/impercar.net\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/impercar.png\" class=\"attachment-full size-full wp-image-96633\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/impercar.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/impercar-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/impercar-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/impercar-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4868fdd e-con-full e-flex e-con e-child\" data-id=\"4868fdd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a5ca950 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"a5ca950\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/fitness-discount.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/fitness.png\" class=\"attachment-full size-full wp-image-96710\" alt=\"fitnessdiscount.com\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/fitness.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/fitness-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d518ff elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"6d518ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.e21.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/e21pg.png\" class=\"attachment-full size-full wp-image-96661\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/e21pg.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/e21pg-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/e21pg-100x100.png 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c82d170 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"c82d170\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.graphicmasters.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/graphicmaster.png\" class=\"attachment-full size-full wp-image-96699\" alt=\"graphicmaster\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/graphicmaster.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/graphicmaster-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4ff20e elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"e4ff20e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.fvmantincendi.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/fvm.png\" class=\"attachment-full size-full wp-image-96700\" alt=\"fvm\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/fvm.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/fvm-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dbeccd elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"1dbeccd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/gesosport.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/gesosport.png\" class=\"attachment-full size-full wp-image-96701\" alt=\"gesosport\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/gesosport.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/gesosport-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ae829e2 e-con-full e-flex e-con e-child\" data-id=\"ae829e2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b586d4d elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"b586d4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.connesi.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/connesi.png\" class=\"attachment-full size-full wp-image-96662\" alt=\"connesi\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/connesi.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/connesi-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/connesi-100x100.png 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-013c47e elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"013c47e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.t-pro.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/t-pro.png\" class=\"attachment-full size-full wp-image-96640\" alt=\"t-pro\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/t-pro.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/t-pro-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/t-pro-100x100.png 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d07dbf2 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"d07dbf2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/grafox.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/grafox.png\" class=\"attachment-full size-full wp-image-96656\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/grafox.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/grafox-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/grafox-100x100.png 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b146cd9 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"b146cd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.wallstreetenglish.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/wallstreetenglish.png\" class=\"attachment-full size-full wp-image-96696\" alt=\"wallstreetenglish\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/wallstreetenglish.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/wallstreetenglish-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11a6a29 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"11a6a29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.htsinformatica.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/tecno.png\" class=\"attachment-full size-full wp-image-96711\" alt=\"hts\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/tecno.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/tecno-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-532710d e-con-full e-flex e-con e-child\" data-id=\"532710d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50abf7c elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"50abf7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.sangallo.it\/it\/index.php\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/sangallo2025.png\" class=\"attachment-full size-full wp-image-96644\" alt=\"sangallo2025\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/sangallo2025.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/sangallo2025-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/sangallo2025-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/sangallo2025-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbadb06 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"cbadb06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.k-sport.tech\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/ksport.png\" class=\"attachment-full size-full wp-image-96658\" alt=\"ksport\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/ksport.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/ksport-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6a9529 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"a6a9529\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.cspromotion.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/cspromotion.png\" class=\"attachment-full size-full wp-image-96673\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/cspromotion.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/cspromotion-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/cspromotion-100x100.png 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd0d19a elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"dd0d19a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.sportservice360.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"241\" height=\"85\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/Logiva.png\" class=\"attachment-full size-full wp-image-96660\" alt=\"Logiva\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af7f4f1 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"af7f4f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/caciotto.png\" class=\"attachment-full size-full wp-image-96652\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/caciotto.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/caciotto-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/06\/caciotto-100x100.png 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e4f6fa e-con-full e-flex e-con e-child\" data-id=\"5e4f6fa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23494ea elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"23494ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/PersichiniGommeCollestrada\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/centrogommeperugia.png\" class=\"attachment-full size-full wp-image-96664\" alt=\"centrogommeperugia\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/centrogommeperugia.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/centrogommeperugia-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/centrogommeperugia-100x100.png 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6136478 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"6136478\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/cronosagency.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/cronoscomunicazione.png\" class=\"attachment-full size-full wp-image-96663\" alt=\"chronoscommunication\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/cronoscomunicazione.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/cronoscomunicazione-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/cronoscomunicazione-100x100.png 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40b2463 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"40b2463\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/farmaciapiandimassiano\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/farmaciapiandimassiano.png\" class=\"attachment-full size-full wp-image-96665\" alt=\"pharmacypiandimassian\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/farmaciapiandimassiano.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/farmaciapiandimassiano-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/farmaciapiandimassiano-100x100.png 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b66be09 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"b66be09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/diegopeoli.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/Diego-Peoli.png\" class=\"attachment-full size-full wp-image-96654\" alt=\"Diego-Peoli\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/Diego-Peoli.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/Diego-Peoli-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/Diego-Peoli-100x100.png 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b81eeb8 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"b81eeb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.pucciufficio.com\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/pucciuffici.png\" class=\"attachment-full size-full wp-image-96666\" alt=\"pucciuffici\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/pucciuffici.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/pucciuffici-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/pucciuffici-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/pucciuffici-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f25bb68 e-con-full e-flex e-con e-child\" data-id=\"f25bb68\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cc47de9 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"cc47de9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.ldsecurityservice.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/Logo_LD.png\" class=\"attachment-full size-full wp-image-96668\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/Logo_LD.png 250w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/Logo_LD-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/Logo_LD-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/Logo_LD-50x50.png 50w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4fa47c elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"c4fa47c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.gryphus.eu\/it\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/logo-gryphus-nuovo.png\" class=\"attachment-full size-full wp-image-96669\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/logo-gryphus-nuovo.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/logo-gryphus-nuovo-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/logo-gryphus-nuovo-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/logo-gryphus-nuovo-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68c1c03 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"68c1c03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.vipgarden.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/LOGO-VIP-GARDEN.png\" class=\"attachment-full size-full wp-image-96679\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/LOGO-VIP-GARDEN.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/LOGO-VIP-GARDEN-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/LOGO-VIP-GARDEN-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/LOGO-VIP-GARDEN-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-198d77a elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"198d77a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.saet.org\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"224\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/saet.png\" class=\"attachment-full size-full wp-image-96688\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/saet.png 225w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/saet-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/saet-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/saet-50x50.png 50w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87907f4 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"87907f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.telonerialcm.com\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/teloneria.png\" class=\"attachment-full size-full wp-image-96694\" alt=\"tarpaulins\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/teloneria.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/teloneria-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/teloneria-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/teloneria-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-caa3fa0 e-con-full e-flex e-con e-child\" data-id=\"caa3fa0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-76f8f7f elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"76f8f7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/BarMattioli\/?locale=it_IT\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"225\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/Bar-Mattioli.png\" class=\"attachment-full size-full wp-image-96674\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/Bar-Mattioli.png 225w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/Bar-Mattioli-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/Bar-Mattioli-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/Bar-Mattioli-50x50.png 50w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3463fb3 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"3463fb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/ristorante_del_golf_perugia\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"280\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/Ristorante-del-golf.png\" class=\"attachment-full size-full wp-image-96677\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/Ristorante-del-golf.png 280w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/Ristorante-del-golf-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/Ristorante-del-golf-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/Ristorante-del-golf-50x50.png 50w\" sizes=\"(max-width: 280px) 100vw, 280px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8937fdf elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"8937fdf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/grafichepaciotti.com\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/Grafiche-Paciotti.png\" class=\"attachment-full size-full wp-image-96649\" alt=\"Grafiche-Paciotti\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/Grafiche-Paciotti.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/Grafiche-Paciotti-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/Grafiche-Paciotti-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/Grafiche-Paciotti-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e38ac85 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"e38ac85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/mlmax.png\" class=\"attachment-full size-full wp-image-96686\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/mlmax.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/mlmax-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/mlmax-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/08\/mlmax-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bce5358 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"bce5358\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.hotelelpatio.com\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/elpatiologo.png\" class=\"attachment-full size-full wp-image-96692\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/elpatiologo.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/elpatiologo-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/elpatiologo-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/elpatiologo-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6a6d376 e-con-full e-flex e-con e-child\" data-id=\"6a6d376\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4677388 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"4677388\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.alutechitaliagroup.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/alutech.png\" class=\"attachment-full size-full wp-image-96675\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/alutech.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/alutech-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/alutech-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/alutech-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c99c7a elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"7c99c7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.verde-giardino.com\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/VERDE-GIARDINO.png\" class=\"attachment-full size-full wp-image-96681\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/VERDE-GIARDINO.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/VERDE-GIARDINO-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/VERDE-GIARDINO-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/VERDE-GIARDINO-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06bc582 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"06bc582\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.padeloneclub.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/LOGO-PADEL-2.png\" class=\"attachment-full size-full wp-image-96683\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/LOGO-PADEL-2.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/LOGO-PADEL-2-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/LOGO-PADEL-2-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/LOGO-PADEL-2-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2d1f67 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"c2d1f67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.metanofoligno.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/cmf.png\" class=\"attachment-full size-full wp-image-96690\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/cmf.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/cmf-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/cmf-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/cmf-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0ab9430 e-con-full e-flex e-con e-child\" data-id=\"0ab9430\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c2fd62 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"6c2fd62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/pr1momarketcorciano\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/10\/primomarket.png\" class=\"attachment-full size-full wp-image-96697\" alt=\"primomarket\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/10\/primomarket.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/10\/primomarket-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/10\/primomarket-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/10\/primomarket-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18c321e elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"18c321e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.pgkperugia.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/10\/pgk.png\" class=\"attachment-full size-full wp-image-96698\" alt=\"pgk\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/10\/pgk.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/10\/pgk-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/10\/pgk-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/10\/pgk-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a224987 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"a224987\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/borgosante.com\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/10\/07_BS_Country.House_Blu.Completo-Borgo-Sante.png\" class=\"attachment-full size-full wp-image-96695\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/10\/07_BS_Country.House_Blu.Completo-Borgo-Sante.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/10\/07_BS_Country.House_Blu.Completo-Borgo-Sante-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/10\/07_BS_Country.House_Blu.Completo-Borgo-Sante-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/10\/07_BS_Country.House_Blu.Completo-Borgo-Sante-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-63df3d4 e-con-full e-flex e-con e-parent\" data-id=\"63df3d4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1c201bc e-con-full e-flex e-con e-child\" data-id=\"1c201bc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-38a79a8 e-con-full e-flex e-con e-child\" data-id=\"38a79a8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-06102a4 elementor-widget elementor-widget-heading\" data-id=\"06102a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">MEDIA PARTNER<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3595b41 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3595b41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-41d3f4e e-con-full e-flex e-con e-child\" data-id=\"41d3f4e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-68133e7 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"68133e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.umbriatv.com\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/umbriatv.png\" class=\"attachment-full size-full wp-image-96702\" alt=\"umbriatv\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/umbriatv.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/umbriatv-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7abe932 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"7abe932\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/corrieredellumbria.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/Logo_Corriere-dellUmbria.png\" class=\"attachment-full size-full wp-image-96704\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/Logo_Corriere-dellUmbria.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/Logo_Corriere-dellUmbria-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/Logo_Corriere-dellUmbria-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/Logo_Corriere-dellUmbria-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-852e9d3 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"852e9d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/radio.corrieredellumbria.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/radiocorriereumbria.png\" class=\"attachment-full size-full wp-image-96705\" alt=\"\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/radiocorriereumbria.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/radiocorriereumbria-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/radiocorriereumbria-100x100.png 100w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/09\/radiocorriereumbria-50x50.png 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c45a05b elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"c45a05b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.perugiatoday.it\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/Perugia-Today-logo.png\" class=\"attachment-full size-full wp-image-96670\" alt=\"Perugia-Today-logo\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/Perugia-Today-logo.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/Perugia-Today-logo-150x150.png 150w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/07\/Perugia-Today-logo-100x100.png 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bcfaf4 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"4bcfaf4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/101media.png\" class=\"attachment-full size-full wp-image-96706\" alt=\"101media\" srcset=\"https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/101media.png 300w, https:\/\/acperugiacalcio.com\/wp-content\/uploads\/2025\/05\/101media-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>SPONSOR SECOND sponsor BACK SPONSOR SECOND BACK SPONSOR SLEEVE SPONSOR SHORT SPONSOR TOP SPONSORS OFFICIAL SPONSOR HOSPITALITY PARTNER CAR PARTNER MEDICAL PARTNER OFFICIAL SUPPLIER MEDIA PARTNER<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-96452","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/acperugiacalcio.com\/en\/wp-json\/wp\/v2\/pages\/96452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acperugiacalcio.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/acperugiacalcio.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/acperugiacalcio.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acperugiacalcio.com\/en\/wp-json\/wp\/v2\/comments?post=96452"}],"version-history":[{"count":3,"href":"https:\/\/acperugiacalcio.com\/en\/wp-json\/wp\/v2\/pages\/96452\/revisions"}],"predecessor-version":[{"id":96733,"href":"https:\/\/acperugiacalcio.com\/en\/wp-json\/wp\/v2\/pages\/96452\/revisions\/96733"}],"wp:attachment":[{"href":"https:\/\/acperugiacalcio.com\/en\/wp-json\/wp\/v2\/media?parent=96452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}